{"id":103,"date":"2019-05-15T17:48:27","date_gmt":"2019-05-15T17:48:27","guid":{"rendered":"https:\/\/www.polane.com\/?page_id=103"},"modified":"2019-07-02T10:18:27","modified_gmt":"2019-07-02T14:18:27","slug":"division-mecanique-lourd","status":"publish","type":"page","link":"https:\/\/www.polane.com\/fr\/services\/division-mecanique-lourd\/","title":{"rendered":"Division m\u00e9canique lourd"},"content":{"rendered":"<section class=\"title_container services petrole\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-md-12\">\n<div class=\"lc-block\">\n<div editable=\"rich\">\n<h1>Division m\u00e9canique lourd<\/h1>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section class=\"content_container services\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-lg-12\" data-aos=\"fade-left\">\n<div class=\"lc-block services-text\">\n<div editable=\"rich\">\n<h2>Division m\u00e9canique lourd<\/h2>\n<p>Toujours \u00e0 la poursuite de l\u2019innovation et dans le but de r\u00e9pondre \u00e0 la demande, nous nous assurons d\u2019\u00eatre toujours \u00e0 jour. Depuis f\u00e9vrier 2019, Polane a ouvert une division de m\u00e9canique de v\u00e9hicule lourd. \u00c9quip\u00e9s \u00e0 la fine pointe de la technologie pour les diff\u00e9rents logiciels, nous sommes disponibles pour faire les diagnostics, la soudure, la maintenance g\u00e9n\u00e9rale, la fabrication de boyaux hydrauliques, l\u2019installation de benne ainsi que le Programme Entretien pr\u00e9ventif (PEP) de toutes vos machineries lourdes.<\/p>\n<p>Nos m\u00e9caniciens certifi\u00e9s sont disponibles de jour et le soir, quelle que soit la complexit\u00e9 afin de votre situation afin de vous apporter une solution.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"lc-block services-btn\">\n<div lc-helper=\"shortcode\" class=\"live-shortcode\"><a href='https:\/\/www.polane.com\/fr\/contact\/' class='btn contact noir'>Demande d&rsquo;information<\/a><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<\/section>\n<section class=\"realisations_slider_container\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-md-12\">\n<div class=\"lc-block\">\n<div lc-helper=\"shortcode\" class=\"live-shortcode realisations_slider\"><div class='realisations_slider_content'><div class='row'><div class='col-12'><h3>Projects<\/h3><\/div><div class='col-12'><div class=\"realisations_slider_slider\"><ul class=\"slides\"><li><a href=\"https:\/\/www.polane.com\/fr\/realisations\/division-mecanique-lourd\/\" class=\"uneRealisation\"><div class=\"realisation-img d-flex align-items-center justify-content-center overflow-hidden\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.polane.com\/wp-content\/uploads\/2019\/07\/IMG_1406-500x500.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><\/a><\/li><li><a href=\"https:\/\/www.polane.com\/fr\/realisations\/division-mecanique-lourd\/\" class=\"uneRealisation\"><div class=\"realisation-img d-flex align-items-center justify-content-center overflow-hidden\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.polane.com\/wp-content\/uploads\/2019\/07\/IMG_1415-500x500.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><\/a><\/li><li><a href=\"https:\/\/www.polane.com\/fr\/realisations\/division-mecanique-lourd\/\" class=\"uneRealisation\"><div class=\"realisation-img d-flex align-items-center justify-content-center overflow-hidden\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.polane.com\/wp-content\/uploads\/2019\/07\/2017-10-21-07.15.24-500x500.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><\/a><\/li><li><a href=\"https:\/\/www.polane.com\/fr\/realisations\/division-mecanique-lourd\/\" class=\"uneRealisation\"><div class=\"realisation-img d-flex align-items-center justify-content-center overflow-hidden\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.polane.com\/wp-content\/uploads\/2019\/07\/IMG_1408-500x500.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><\/a><\/li><li><a href=\"https:\/\/www.polane.com\/fr\/realisations\/division-mecanique-lourd\/\" class=\"uneRealisation\"><div class=\"realisation-img d-flex align-items-center justify-content-center overflow-hidden\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.polane.com\/wp-content\/uploads\/2019\/07\/IMG_1504-500x500.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><\/a><\/li><li><a href=\"https:\/\/www.polane.com\/fr\/realisations\/division-mecanique-lourd\/\" class=\"uneRealisation\"><div class=\"realisation-img d-flex align-items-center justify-content-center overflow-hidden\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.polane.com\/wp-content\/uploads\/2019\/07\/IMG_1402-500x500.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/div><\/a><\/li><\/ul><\/div><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Division m\u00e9canique lourd Division m\u00e9canique lourd Toujours \u00e0 la poursuite de l\u2019innovation et dans le but de r\u00e9pondre \u00e0 la demande, nous nous assurons d\u2019\u00eatre toujours \u00e0 jour. Depuis f\u00e9vrier 2019, Polane a ouvert une division de m\u00e9canique de v\u00e9hicule lourd. \u00c9quip\u00e9s \u00e0 la fine pointe de la technologie pour les diff\u00e9rents logiciels, nous sommes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":72,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/empty.php","meta":{"footnotes":""},"class_list":["post-103","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.polane.com\/fr\/wp-json\/wp\/v2\/pages\/103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.polane.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.polane.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.polane.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polane.com\/fr\/wp-json\/wp\/v2\/comments?post=103"}],"version-history":[{"count":14,"href":"https:\/\/www.polane.com\/fr\/wp-json\/wp\/v2\/pages\/103\/revisions"}],"predecessor-version":[{"id":677,"href":"https:\/\/www.polane.com\/fr\/wp-json\/wp\/v2\/pages\/103\/revisions\/677"}],"up":[{"embeddable":true,"href":"https:\/\/www.polane.com\/fr\/wp-json\/wp\/v2\/pages\/72"}],"wp:attachment":[{"href":"https:\/\/www.polane.com\/fr\/wp-json\/wp\/v2\/media?parent=103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}